{"id":905,"date":"2023-10-15T13:54:40","date_gmt":"2023-10-15T13:54:40","guid":{"rendered":"https:\/\/datalogics.co.in\/?page_id=905"},"modified":"2023-10-23T20:23:42","modified_gmt":"2023-10-23T20:23:42","slug":"order-form","status":"publish","type":"page","link":"https:\/\/datalogics.co.in\/index.php\/order-form\/","title":{"rendered":"Order Form"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"905\" class=\"elementor elementor-905\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-45d072e e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"45d072e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-801876b elementor-widget elementor-widget-spacer\" data-id=\"801876b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5dbba5ea elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no\" data-id=\"5dbba5ea\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6605c92\" data-id=\"6605c92\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-81eff91 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no\" data-id=\"81eff91\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6c6a10c\" data-id=\"6c6a10c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-071987d\" data-id=\"071987d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc0a572 elementor-widget elementor-widget-heading\" data-id=\"fc0a572\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">We are here to assist you<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22fb19b elementor-widget elementor-widget-text-editor\" data-id=\"22fb19b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Share the below information about you. Our team will reach you for further steps.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-afa1b8e\" data-id=\"afa1b8e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5ff57e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no\" data-id=\"5ff57e1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2206137\" data-id=\"2206137\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-54b74e5\" data-id=\"54b74e5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58de3e3 elementor-widget elementor-widget-ha-wpform happy-addon ha-wpform\" data-id=\"58de3e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ha-wpform.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style id=\"wpforms-css-vars-885\">\n\t\t\t\t#wpforms-885 {\n\t\t\t\t\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-885\"><form id=\"wpforms-form-885\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"885\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/905\" data-token=\"2209fc17bc810ced8a058b64fb717c11\" data-token-time=\"1778676277\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-885-field_56-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-inline\" data-field-id=\"56\"><fieldset><legend class=\"wpforms-field-label\">Product <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-885-field_56\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-885-field_56_1\" name=\"wpforms[fields][56][]\" value=\"CloudPay\" aria-errormessage=\"wpforms-885-field_56_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-885-field_56_1\">CloudPay<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-885-field_56_2\" name=\"wpforms[fields][56][]\" value=\"E-Invoice\" aria-errormessage=\"wpforms-885-field_56_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-885-field_56_2\">E-Invoice<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-885-field_56_3\" name=\"wpforms[fields][56][]\" value=\"Website\" aria-errormessage=\"wpforms-885-field_56_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-885-field_56_3\">Website<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-885-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><fieldset><legend class=\"wpforms-field-label\">Contact Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-885-field_1\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][1][first]\" aria-errormessage=\"wpforms-885-field_1-error\" required><label for=\"wpforms-885-field_1\" class=\"wpforms-field-sublabel after\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-885-field_1-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][1][last]\" value=\"-\" aria-errormessage=\"wpforms-885-field_1-last-error\" required><label for=\"wpforms-885-field_1-last\" class=\"wpforms-field-sublabel after\">Last<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-885-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-885-field_2\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-885-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" spellcheck=\"false\" aria-errormessage=\"wpforms-885-field_2-error\" required><\/div><div id=\"wpforms-885-field_46-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"46\"><label class=\"wpforms-field-label\" for=\"wpforms-885-field_46\">Phone Number <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-885-field_46\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][46]\" aria-errormessage=\"wpforms-885-field_46-error\" required><\/div><div id=\"wpforms-885-field_33-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"33\"><label class=\"wpforms-field-label\" for=\"wpforms-885-field_33\">Company\/Firm\/Legal Entity Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-885-field_33\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][33]\" aria-errormessage=\"wpforms-885-field_33-error\" required><\/div><div id=\"wpforms-885-field_57-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"57\"><label class=\"wpforms-field-label\" for=\"wpforms-885-field_57\">GST Number <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-885-field_57\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][57]\" placeholder=\"GST Number\" aria-errormessage=\"wpforms-885-field_57-error\" required><\/div><div id=\"wpforms-885-field_47-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"47\"><label class=\"wpforms-field-label\" for=\"wpforms-885-field_47\">Address Line 1 <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-885-field_47\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][47]\" placeholder=\"Address Line 1\" aria-errormessage=\"wpforms-885-field_47-error\" required><\/div><div id=\"wpforms-885-field_48-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"48\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-885-field_48\" aria-hidden=\"false\">Address Line 2<\/label><input type=\"text\" id=\"wpforms-885-field_48\" class=\"wpforms-field-medium\" name=\"wpforms[fields][48]\" placeholder=\"Address Line 2\" aria-errormessage=\"wpforms-885-field_48-error\" ><\/div><div id=\"wpforms-885-field_49-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"49\"><label class=\"wpforms-field-label\" for=\"wpforms-885-field_49\">City <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-885-field_49\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][49]\" aria-errormessage=\"wpforms-885-field_49-error\" required><\/div><div id=\"wpforms-885-field_50-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"50\"><label class=\"wpforms-field-label\" for=\"wpforms-885-field_50\">State \/ Province \/ Region <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-885-field_50\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][50]\" aria-errormessage=\"wpforms-885-field_50-error\" required><\/div><div id=\"wpforms-885-field_51-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"51\"><label class=\"wpforms-field-label\" for=\"wpforms-885-field_51\">Postal Code <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-885-field_51\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][51]\" aria-errormessage=\"wpforms-885-field_51-error\" required><\/div><div id=\"wpforms-885-field_52-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"52\"><label class=\"wpforms-field-label\" for=\"wpforms-885-field_52\">Country <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-885-field_52\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][52]\" aria-errormessage=\"wpforms-885-field_52-error\" required><\/div><div id=\"wpforms-885-field_7-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-885-field_7\">Few words about your organization<\/label><textarea id=\"wpforms-885-field_7\" class=\"wpforms-field-medium\" name=\"wpforms[fields][7]\" aria-errormessage=\"wpforms-885-field_7-error\" ><\/textarea><\/div><div id=\"wpforms-885-field_61-container\" class=\"wpforms-field wpforms-field-number-slider\" data-field-id=\"61\"><label class=\"wpforms-field-label\" for=\"wpforms-885-field_61\">No. of Employees<\/label>\n<input\n\ttype=\"range\"\n\tid=\"wpforms-885-field_61\" class=\"wpforms-field-medium\" name=\"wpforms[fields][61]\" value=\"500\" aria-errormessage=\"wpforms-885-field_61-error\"\t\tmin=\"10\"\n\tmax=\"15000\"\n\tstep=\"100\">\n\n<div class=\"wpforms-field-number-slider-hint\"\n\tdata-hint=\"{value}\">\n\t<b>500<\/b><\/div>\n<\/div><div id=\"wpforms-885-field_65-container\" class=\"wpforms-field wpforms-field-number-slider\" data-field-id=\"65\"><label class=\"wpforms-field-label\" for=\"wpforms-885-field_65\">No. of Invoice Per Year<\/label>\n<input\n\ttype=\"range\"\n\tid=\"wpforms-885-field_65\" class=\"wpforms-field-medium\" name=\"wpforms[fields][65]\" value=\"10\" aria-errormessage=\"wpforms-885-field_65-error\"\t\tmin=\"10\"\n\tmax=\"10000\"\n\tstep=\"10\">\n\n<div class=\"wpforms-field-number-slider-hint\"\n\tdata-hint=\"{value}\">\n\t<b>10<\/b><\/div>\n<\/div><div id=\"wpforms-885-field_64-container\" class=\"wpforms-field wpforms-field-radio\" data-field-id=\"64\"><fieldset><legend class=\"wpforms-field-label\">Company Turnover <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-885-field_64\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-885-field_64_1\" name=\"wpforms[fields][64]\" value=\"Below 5 Cr.\" aria-errormessage=\"wpforms-885-field_64_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-885-field_64_1\">Below 5 Cr.<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-885-field_64_2\" name=\"wpforms[fields][64]\" value=\"Above 5 Cr.\" aria-errormessage=\"wpforms-885-field_64_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-885-field_64_2\">Above 5 Cr.<\/label><\/li><\/ul><\/fieldset><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"885\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/datalogics.co.in\/index.php\/wp-json\/wp\/v2\/pages\/905\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-885\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img decoding=\"async\" src=\"https:\/\/datalogics.co.in\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>We are here to assist you Share the below information about you. Our team will reach you for further steps. Please enable JavaScript in your browser to complete this form.Please enable JavaScript in your browser to complete this form. Product * CloudPay E-Invoice Website Contact Name * FirstLast Email *Phone Number *Company\/Firm\/Legal Entity Name *GST NumberAddress *Single Line TextCity *State \/ Province \/ Region *Postal Code *Country *Special InstructionsNo. of Employees Selected Value: 300 No. of Invoice Per Year Selected Value: 300 Company Turnover * Below 5 Cr. Above 5 Cr. Submit<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-905","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/datalogics.co.in\/index.php\/wp-json\/wp\/v2\/pages\/905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/datalogics.co.in\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/datalogics.co.in\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/datalogics.co.in\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/datalogics.co.in\/index.php\/wp-json\/wp\/v2\/comments?post=905"}],"version-history":[{"count":72,"href":"https:\/\/datalogics.co.in\/index.php\/wp-json\/wp\/v2\/pages\/905\/revisions"}],"predecessor-version":[{"id":1188,"href":"https:\/\/datalogics.co.in\/index.php\/wp-json\/wp\/v2\/pages\/905\/revisions\/1188"}],"wp:attachment":[{"href":"https:\/\/datalogics.co.in\/index.php\/wp-json\/wp\/v2\/media?parent=905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}